{"id":7707,"date":"2023-10-04T21:20:57","date_gmt":"2023-10-04T21:20:57","guid":{"rendered":"https:\/\/monpsychomag.com\/?p=7707"},"modified":"2023-10-04T21:20:59","modified_gmt":"2023-10-04T21:20:59","slug":"sante-mentale-chez-les-femmes-influence-des-roles-de-genre","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2023\/10\/04\/sante-mentale-chez-les-femmes-influence-des-roles-de-genre\/","title":{"rendered":"Sant\u00e9 mentale chez les femmes : Influence des r\u00f4les de genre."},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p>La sant\u00e9 mentale des femmes est un sujet important et complexe. Les femmes peuvent \u00eatre confront\u00e9es \u00e0 des d\u00e9fis sp\u00e9cifiques qui affectent leur bien-\u00eatre mental, tels que les pressions sociales, les r\u00f4les de genre, la maternit\u00e9, la violence de genre, et bien d&rsquo;autres. Il est essentiel de sensibiliser \u00e0 ces questions, de promouvoir l&rsquo;acc\u00e8s aux soins de sant\u00e9 mentale et de soutenir les femmes pour qu&rsquo;elles puissent maintenir une bonne sant\u00e9 mentale.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment les r\u00f4les du genre influent-ils n\u00e9gativement sur la sant\u00e9 mentale des femmes ?<\/h2>\n\n\n\n<p>Les r\u00f4les de genre peuvent avoir un impact n\u00e9gatif sur la sant\u00e9 mentale des femmes de plusieurs mani\u00e8res. En six grands points nous vous faisons d\u00e9couvrir comment cela arrive.<\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Pressions sociales<\/strong> : Les attentes sociales concernant le comportement des femmes comme la n\u00e9cessit\u00e9 d&rsquo;\u00eatre \u00ab\u00a0parfaites\u00a0\u00bb en tant que m\u00e8res, partenaires et professionnelles, peuvent entra\u00eener un stress excessif et de l&rsquo;anxi\u00e9t\u00e9.<\/li>\n\n\n\n<li><strong>Discrimination<\/strong> : Les femmes peuvent faire face \u00e0 la discrimination bas\u00e9e sur leur genre, ce qui peut provoquer de la d\u00e9pression, de l&rsquo;anxi\u00e9t\u00e9 et une faible estime de soi.<\/li>\n\n\n\n<li><strong>Violence de genre<\/strong> : Les femmes sont plus susceptibles d&rsquo;\u00eatre victimes de violence de genre, ce qui peut entra\u00eener des traumatismes et des probl\u00e8mes de sant\u00e9 mentale \u00e0 long terme.<\/li>\n\n\n\n<li><strong>In\u00e9galit\u00e9s \u00e9conomiques<\/strong> : Les in\u00e9galit\u00e9s salariales et professionnelles peuvent contribuer au stress financier, \u00e0 la d\u00e9pendance \u00e9conomique, et ainsi augmenter les niveaux de stress et d&rsquo;anxi\u00e9t\u00e9.<\/li>\n\n\n\n<li><strong>Stigmatisation de la sant\u00e9 mentale <\/strong>: Les femmes peuvent \u00eatre plus sujettes \u00e0 la stigmatisation lorsqu&rsquo;elles cherchent de l&rsquo;aide pour des probl\u00e8mes de sant\u00e9 mentale en raison de normes sociales restrictives.<\/li>\n\n\n\n<li><strong>Charge mentale<\/strong> : Les femmes peuvent \u00eatre confront\u00e9es \u00e0 une charge mentale disproportionn\u00e9e, laquelle est li\u00e9e \u00e0 la gestion des responsabilit\u00e9s familiales et domestiques, ce qui peut \u00eatre \u00e9puisant mentalement.<\/li>\n<\/ol>\n\n\n\n<p>Il est important de reconna\u00eetre ces d\u00e9fis et de travailler \u00e0 \u00e9liminer les in\u00e9galit\u00e9s de genre, \u00e0 soutenir l&rsquo;autonomie des femmes et \u00e0 promouvoir des environnements o\u00f9 elles peuvent s&rsquo;\u00e9panouir sur le plan mental. L&rsquo;acc\u00e8s \u00e0 des soins de sant\u00e9 mentale appropri\u00e9s et \u00e0 un r\u00e9seau de soutien solide est \u00e9galement essentiel.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>La sant\u00e9 mentale des femmes est un sujet important et complexe. Les femmes peuvent \u00eatre confront\u00e9es \u00e0 des d\u00e9fis sp\u00e9cifiques qui affectent leur bien-\u00eatre mental, tels que les pressions sociales, les r\u00f4les de genre, la maternit\u00e9, la violence de genre, et bien d&rsquo;autres.<\/p>\n","protected":false},"author":127,"featured_media":7702,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[332,849],"tags":[152,1350,285],"class_list":["post-7707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bien-etre","category-sante","tag-femmes","tag-genre","tag-sante-mentale"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-22-at-13.25.01.jpeg?fit=1000%2C667&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/7707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=7707"}],"version-history":[{"count":1,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/7707\/revisions"}],"predecessor-version":[{"id":7708,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/7707\/revisions\/7708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/7702"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=7707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=7707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=7707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}