{"id":7424,"date":"2024-07-12T21:31:46","date_gmt":"2024-07-12T21:31:46","guid":{"rendered":"https:\/\/monpsychomag.com\/?p=7424"},"modified":"2024-07-12T21:36:50","modified_gmt":"2024-07-12T21:36:50","slug":"le-trauma-de-la-fausse-couche-en-afrique-ta-route-vers-la-guerison","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2024\/07\/12\/le-trauma-de-la-fausse-couche-en-afrique-ta-route-vers-la-guerison\/","title":{"rendered":"Le trauma de la fausse couche en Afrique : ta route vers la gu\u00e9rison"},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p class=\"has-text-align-justify\"><em>\u00ab J\u2019ai pleur\u00e9 en pensant \u00e0 ce que j\u2019avais perdu et je me suis demand\u00e9 si je pourrais un jour me relever de cette douleur. \u00bb<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Une fausse couche est une perte. Qu&rsquo;importe l&rsquo;\u00e2ge qu&rsquo;on a ou les circonstances de la perte, subir une fausse couche a des impacts psychologiques sur la femme, le couple et l&rsquo;entourage. On remarque qu&rsquo;en Afrique la fausse couche n&rsquo;est pas abord\u00e9e de la m\u00eame mani\u00e8re et l\u00e0 o\u00f9 sous d&rsquo;autres cieux les femmes qui subissent une fausse couche sont automatiquement prises en charge psychologiquement, ici elles ont tendance \u00e0 le subir toute seule. Comment peut-on donc s&rsquo;en remettre ?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu&rsquo;est-ce qu&rsquo;une fausse couche ?<\/h2>\n\n\n\n<p class=\"has-text-align-justify\">La fausse couche est une interruption spontan\u00e9e de grossesse qui survient au cours des 5 premiers mois. Elle se manifeste par des saignements vaginaux accompagn\u00e9s de fortes douleurs dans la partie basse du ventre.<\/p>\n\n\n\n<p>La fausse couche est un \u00e9v\u00e9nement traumatisant qui affecte chaque femme diff\u00e9remment. Selon le <strong><a href=\"https:\/\/www.figo.org\/fr\" data-type=\"link\" data-id=\"https:\/\/www.figo.org\/fr\">FIGO<\/a><\/strong>, \u00e0 l&rsquo;\u00e9chelle mondiale, environ 12 \u00e0 15% des grossesses reconnues se terminent par une fausse couche.<\/p>\n\n\n\n<p>En Afrique, une fausse couche peut \u00eatre per\u00e7ue diff\u00e9remment en raison de diverses croyances culturelles et sociales. Le choc initial est intensifi\u00e9 par quelques \u00e9l\u00e9ments :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Une douleur invisibilis\u00e9e :<\/strong> En Afrique, il est souvent difficile de parler ouvertement de la fausse couche. Les croyances culturelles peuvent pousser les femmes \u00e0 cacher leur douleur, pensant que c\u2019est un sujet de honte ou de malchance.<\/li>\n\n\n\n<li><strong>La pression de l\u2019environnement :<\/strong> Dans certaines communaut\u00e9s, il existe une pression sociale forte pour avoir des enfants et continuer la lign\u00e9e familiale. Cette pression rend encore plus difficile l\u2019expression de la tristesse et le besoin de soutien.<\/li>\n\n\n\n<li><strong>L&rsquo;acc\u00e8s limit\u00e9 aux services de soutien :<\/strong> Les services de sant\u00e9 mentale et les groupes de soutien peuvent \u00eatre rares ou inaccessibles dans certaines r\u00e9gions d\u2019Afrique.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Comment les femmes le vivent-elles ?<\/h2>\n\n\n\n<p>Apr\u00e8s le choc initial, les \u00e9motions sont souvent complexes et douloureuses. Ces sentiments sont amplifi\u00e9s par le contexte social et culturel africain. Outre la douleur physique qu&rsquo;elle engendre, la fausse-couche peut entra\u00eener une douleur morale, traduite par une morbidit\u00e9 psychologique chez les femmes avec l&rsquo;apparition de sympt\u00f4mes anxieux, d\u00e9pressifs, ou encore un stress post-traumatique. On peut retrouver notamment ces sentiments :<\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Le deuil non exprim\u00e9 :<\/strong> Dans de nombreuses cultures africaines, l\u2019expression de la douleur est souvent r\u00e9prim\u00e9e. La fausse couche devient un <strong><a href=\"https:\/\/monpsychomag.com\/index.php\/2021\/10\/07\/le-deuil-en-5-etapes\/\" data-type=\"post\" data-id=\"5273\">deuil silencieux<\/a><\/strong>, avec peu d\u2019espace pour l\u2019expression des \u00e9motions.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Le poids de la culpabilit\u00e9 :<\/strong> La culpabilit\u00e9 est une \u00e9motion courante, exacerb\u00e9e par des croyances qui peuvent bl\u00e2mer la femme pour la perte. Les femmes peuvent se demander ce qu\u2019elles auraient pu faire diff\u00e9remment.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>La col\u00e8re et la confusion :<\/strong> Le sentiment de col\u00e8re envers soi-m\u00eame, les circonstances, ou m\u00eame la vie elle-m\u00eame est souvent intense et peut \u00eatre mal compris dans un contexte o\u00f9 les \u00e9motions sont rarement partag\u00e9es ouvertement.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Comment se remettre d&rsquo;une fausse couche ?<\/h2>\n\n\n\n<p>M\u00eame s&rsquo;il est impensable qu&rsquo;on puisse s&rsquo;en remettre, voici quelques moyens vers la gu\u00e9rion apr\u00e8s une fausse couche : <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">1. <strong>Exprimer ses \u00e9motions :<\/strong> <\/h4>\n\n\n\n<p>Ne pas garder sa douleur pour soi. Il existe des moyens de commencer \u00e0 partager son histoire et \u00e0 trouver du soutien \u00e0 travers l&rsquo;entourage. Parler avec des a\u00een\u00e9s ou des <strong><a href=\"https:\/\/www.larousse.fr\/dictionnaires\/francais\/mentor\/50535\">mentors <\/a><\/strong>pourquoi pas ? L&rsquo;essentiel est de chercher des personnes qui peuvent offrir une forme de soutien et de r\u00e9confort.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">2. <strong>Prendre soin de soi : <\/strong><\/h4>\n\n\n\n<p>Adopter des<strong><a href=\"https:\/\/monpsychomag.com\/index.php\/2020\/11\/24\/dix-instructions-pour-une-meditation-basee-sur-le-souffle\/\" data-type=\"post\" data-id=\"1196\"> pratiques de bien-\u00eatre <\/a><\/strong>en priorisant sa sant\u00e9 mentale et physique est un prochain pas vers la gu\u00e9rison.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">3. <strong>Cr\u00e9er un rituel de souvenir : <\/strong><\/h4>\n\n\n\n<p>Donner un sens \u00e0 la perte en honorant ce qu&rsquo;on a perdu de mani\u00e8re significative. Cr\u00e9er un rituel de souvenir comme une c\u00e9r\u00e9monie, un espace de r\u00e9flexion, ou une action symbolique pour marquer la perte peut \u00e9galement vous aider \u00e0 faire le deuil.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">4. <strong>Chercher de l\u2019aide professionnelle : <\/strong><\/h4>\n\n\n\n<p>Oser demander de l\u2019aide d\u00e9montre qu&rsquo;on d\u00e9cide de ne pas rester pas seule avec sa douleur. Des ressources sont disponibles pour. Consulter un psychologue, m\u00eame en ligne si n\u00e9cessaire, peut vous aider \u00e0 aller de l&rsquo;avant.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La fausse couche n\u2019est pas seulement une perte physique ; c\u2019est une montagne de douleur \u00e9motionnelle souvent invisible aux yeux des autres. <strong>Rappellez-vous : Vous n&rsquo;\u00eates pas seule dans cette \u00e9preuve. Des ressources, du soutien et des moyens de gu\u00e9rison sont disponibles. Ose faire le premier pas vers la gu\u00e9rison aujourd&rsquo;hui.<\/strong><\/p>\n\n\n\n<p>Prenez rendez-vous d\u00e8s \u00e0 pr\u00e9sent ici : <a href=\"https:\/\/monpsychomag.com\/index.php\/rendez-vous\/\" data-type=\"page\" data-id=\"6193\"><strong>Prise de rendez-vous<\/strong><\/a><\/p>\n\n\n\n<p>Le meilleur s&rsquo;installe en vous.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00ab J\u2019ai pleur\u00e9 en pensant \u00e0 ce que j\u2019avais perdu et je me suis demand\u00e9 si je pourrais un jour me relever de cette douleur. \u00bb<br \/>\nUne fausse couche est une perte. Qu&rsquo;importe l&rsquo;\u00e2ge qu&rsquo;on a ou les circonstances de la perte, subir une fausse couche a des impacts psychologiques sur la femme, le couple et l&rsquo;entourage. On remarque qu&rsquo;en Afrique la fausse couche n&rsquo;est pas abord\u00e9e&#8230;<\/p>\n","protected":false},"author":129,"featured_media":8510,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[332,401],"tags":[941,280,87,1439,304,1165,28,324],"class_list":["post-7424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bien-etre","category-couple","tag-afrique","tag-choc","tag-couple","tag-fausse-couche","tag-femme","tag-guerison","tag-psychologue","tag-traumatisme"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2024\/07\/39cf0df8c8-e1720815431838.jpg?fit=800%2C534&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/7424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=7424"}],"version-history":[{"count":3,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/7424\/revisions"}],"predecessor-version":[{"id":8513,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/7424\/revisions\/8513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/8510"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=7424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=7424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=7424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}