{"id":7090,"date":"2022-12-07T17:21:17","date_gmt":"2022-12-07T17:21:17","guid":{"rendered":"https:\/\/monpsychomag.com\/?p=7090"},"modified":"2022-12-07T17:21:17","modified_gmt":"2022-12-07T17:21:17","slug":"comment-faire-face-aux-disputes-de-ses-parents","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2022\/12\/07\/comment-faire-face-aux-disputes-de-ses-parents\/","title":{"rendered":"Comment faire face aux disputes de ses parents ?"},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p class=\"has-text-align-justify\">Vos <a href=\"https:\/\/monpsychomag.com\/index.php\/2022\/02\/08\/voici-pourquoi-les-enfants-ne-doivent-pas-assister-aux-disputes-entre-les-parents\/\" data-type=\"post\" data-id=\"6102\">parents<\/a> se querellent-ils souvent\u00a0? Leurs disputes deviennent-elles vraiment intenses\u00a0? Voir ses parents se disputer constitue une exp\u00e9rience tr\u00e8s difficile \u00e0 vivre, mais il existe des mesures que vous avez la possibilit\u00e9 de prendre afin de vous prot\u00e9ger contre le conflit, les aider \u00e0 comprendre la fa\u00e7on dont leurs comportements vous affectent et g\u00e9rer les cons\u00e9quences d&rsquo;une dispute.<\/p>\n\n\n\n<h2 class=\"has-text-align-justify wp-block-heading\">1 <strong>Restez neutre<\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-justify\">Vous ne devriez pas devenir le centre de la dispute. Ne prenez pas position et essayez de rester compl\u00e8tement \u00e0 l&rsquo;\u00e9cart. Vous n&rsquo;avez pas \u00e0 arbitrer.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Si l&rsquo;un de vos parents tente de vous entrainer dans la dispute, soyez honn\u00eate et dites-lui que vous n&rsquo;avez pas envie de choisir de camp. Vous en avez le droit.<\/p>\n\n\n\n<h2 class=\"has-text-align-justify wp-block-heading\">2 <strong>Trouvez un abri chez vous<\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-justify\">Il importe que vous ayez un sanctuaire o\u00f9 vous avez la possibilit\u00e9 de vous r\u00e9fugier au cas o\u00f9 les disputes deviendraient trop stressantes. Disposer d&rsquo;un endroit o\u00f9 vous rendre peut vous \u00e9viter de voir ou d&rsquo;entendre ces disputes intenses. Prenez en compte ces quelques options\u00a0:<\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<p class=\"has-text-align-justify\">Passez du temps dans l&rsquo;arri\u00e8re-cour au cas o\u00f9 vous en disposeriez si vous avez une chambre individuelle qui peut vous emp\u00eacher d&rsquo;entendre la dispute, entrez-y.<\/p>\n\n\n\n<h2 class=\"has-text-align-justify wp-block-heading\">3 <strong>Allez dans la maison d&rsquo;une autre personne<\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-justify\">Si vous n&rsquo;avez pas un lieu s\u00e9curis\u00e9 dans votre maison, allez ailleurs. Essayez d&rsquo;aller chez un voisin qui n&rsquo;est pas loin de vous. Vous pourriez \u00e9galement vous rendre chez un ami ou un proche \u00e0 pied, \u00e0 v\u00e9lo ou en voiture, selon la distance.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4 <strong>Entretenez des relations saines<\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-justify\">L&rsquo;une des meilleures mani\u00e8res de vous prot\u00e9ger contre le stress d&rsquo;avoir des parents qui se disputent, c&rsquo;est de cr\u00e9er vos relations personnelles. Les recherches ont montr\u00e9 qu&rsquo;un soutien social ferme est b\u00e9n\u00e9fique pour la sant\u00e9. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Vous avez m\u00eame la possibilit\u00e9 de cr\u00e9er des relations positives si vos g\u00e9niteurs n&rsquo;ont pas \u00e9t\u00e9 d&rsquo;excellents mod\u00e8les. Cela pourrait demander un minimum de travail, mais tant que vous vous focalisez sur les aspects importants comme la confiance et la communication, vous \u00e9chapperez au cycle des relations nuisibles.<\/p>\n\n\n\n<p><strong><em>Sources : <a href=\"https:\/\/fr.wikihow.com\/faire-face-aux-disputes-de-ses-parents\">vivre avec les parents qui se disputent<\/a><\/em><\/strong><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Vos parents se querellent-ils souvent\u00a0? Leurs disputes deviennent-elles vraiment intenses\u00a0?<\/p>\n","protected":false},"author":122,"featured_media":7091,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[402],"tags":[107,211],"class_list":["post-7090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-monpsychomag","tag-parents"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2022\/12\/Dispute-Parents-e1670433646184.jpg?fit=800%2C534&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/7090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/122"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=7090"}],"version-history":[{"count":1,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/7090\/revisions"}],"predecessor-version":[{"id":7092,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/7090\/revisions\/7092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/7091"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=7090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=7090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=7090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}