{"id":4579,"date":"2021-08-30T09:00:10","date_gmt":"2021-08-30T09:00:10","guid":{"rendered":"http:\/\/monpsychomag.com\/?p=4579"},"modified":"2021-08-30T10:31:25","modified_gmt":"2021-08-30T10:31:25","slug":"a-partir-de-quel-moment-boire-lalcool-devient-pathologique","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2021\/08\/30\/a-partir-de-quel-moment-boire-lalcool-devient-pathologique\/","title":{"rendered":"A partir de quel moment, boire l&rsquo;alcool devient pathologique ?"},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p class=\"has-text-align-justify\">La question pos\u00e9e fr\u00e9quemment par les consommateurs, ou leur entourage, est <strong><em>\u00e0 partir de quel moment ou de quelle quantit\u00e9 une conduite devient-elle<\/em><\/strong><strong> <\/strong><strong><em>excessive, nuisible, \u00e0 risque ou pathologique ?<\/em><\/strong><em> <\/em>Finalement, \u00e0 partir de quel moment doit-on s\u2019inqui\u00e9ter ? Il est difficile de r\u00e9pondre \u00e0 cette question. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">S\u2019il est assez ais\u00e9 de reconna\u00eetre une conduite tr\u00e8s nuisible ou d\u00e9pendante, il est par contre difficile de d\u00e9terminer \u00e0 partir de quel moment ou quelle limite on passe d\u2019une <strong>consommation sans risque<\/strong> \u00e0 une <strong>consommation nuisible<\/strong>. Il n\u2019y a pas de<strong> <\/strong><strong><em>deadline<\/em><\/strong><em> <\/em>pr\u00e9cise. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les crit\u00e8res<\/h3>\n\n\n\n<p class=\"has-text-align-justify\">Goodman (1990) utilise plusieurs crit\u00e8res pour d\u00e9finir la <a href=\"https:\/\/r.search.yahoo.com\/cbclk2\/dWU9MTM3OTU0MDE2MjgzNEY3OCZ1dD0xNjMwMzE2MjIyMjE1JnVvPTcxODEyMDE3MTcxNDgxJmx0PTImcz0xJmVzPU1wUGMxVGtHUFMuTWNvWmRZRk4wMjdaWlptMFBabkNVSVBaUWswQjFtRlFfblpQLg--\/RV=2\/RE=1630345022\/RO=10\/RU=https%3a%2f%2fwww.bing.com%2faclick%3fld%3de8g20jIC0FqvuNG-9A33n9ajVUCUzOYUdNMWdJhISzyDgMJbWzkYJuebfLuWUxJou0WDrAAiQdMjtkA8vCbafIEuEn-QwzMs5wXBxTGYdIBOZLfodNiyLhlFs3bW6ZhFwhcaRayKkHJhwYu1vuC9QkhhfHhIvlKy4WfpUEG0QIbetsqaMmw41DS-ghzMrM2HHjNYKchA%26u%3daHR0cHMlM2ElMmYlMmZ3d3cuc3VwZXItc21hcnQuZXUlMmZhcnRpY2xlLnBsJTNmaWQlM2QwNDgzJTI2bGFuZyUzZGZyJTI2ZnJvbWlkJTNkQkIxMzJORVclMjZtc2Nsa2lkJTNkMjI5Y2M1MTRiNGNkMWQ4MjgwNmNhNDM4MTI3M2YyYWI%26rlid%3d229cc514b4cd1d82806ca4381273f2ab\/RK=2\/RS=bswqRsl3.AnohTS0dhj0JM9GXMc-;_ylt=AwrJQ6C.pixhfCYAUFok24lQ;_ylu=Y29sbwNpcjIEcG9zAzEEdnRpZAMEc2VjA292LXRvcA--;_ylc=X3IDMgRydAMw?IG=0ac943a071514d7da800000000bbbf19\"><strong>d\u00e9pendance<\/strong><\/a> avec produit ou sans produit :<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Impossibilit\u00e9 de r\u00e9sister aux impulsions \u00e0 r\u00e9aliser un type de comportement ; sensation croissante de tension pr\u00e9c\u00e9dant imm\u00e9diatement le d\u00e9but du comportement ; plaisir ou soulagement pendant sa dur\u00e9e ; sensation de perte de contr\u00f4le ; pr\u00e9sence d\u2019au moins cinq des neuf crit\u00e8res suivants :<\/p>\n\n\n\n<p class=\"has-text-align-justify\">1. pr\u00e9occupation fr\u00e9quente au sujet du comportement ou de sa pr\u00e9paration,<\/p>\n\n\n\n<p>2. intensit\u00e9 et dur\u00e9e des \u00e9pisodes plus importantes que souhait\u00e9es \u00e0 l\u2019origine,<\/p>\n\n\n\n<p>3. tentatives r\u00e9p\u00e9t\u00e9es pour r\u00e9duire, contr\u00f4ler ou abandonner le comportement,<\/p>\n\n\n\n<p>4. temps important consacr\u00e9 \u00e0 pr\u00e9parer les \u00e9pisodes, \u00e0 les entreprendre ou \u00e0 s\u2019en remettre,<\/p>\n\n\n\n<p>5. survenue fr\u00e9quente des \u00e9pisodes lorsque le sujet doit accomplir des obligations professionnelles, scolaires ou universitaires, familiales ou sociales,<\/p>\n\n\n\n<p>6. activit\u00e9s sociales, professionnelles ou r\u00e9cr\u00e9atives majeures sacrifi\u00e9es du fait du comportement,<\/p>\n\n\n\n<p>7. perp\u00e9tuation du comportement, bien que le sujet sache qu\u2019il cause ou aggrave un probleme persistant ou r\u00e9current d\u2019ordre social, financier, psychologique ou psychique,<\/p>\n\n\n\n<p>8. tol\u00e9rance marqu\u00e9e : besoin d\u2019augmenter l\u2019intensit\u00e9 ou la fr\u00e9quence pour obtenir l\u2019effet d\u00e9sir\u00e9, ou diminution de l\u2019effet procur\u00e9 par un comportement de m\u00eame intensit\u00e9,<\/p>\n\n\n\n<p>9. agitation ou irritabilit\u00e9 en cas d\u2019impossibilit\u00e9 de s\u2019adonner au comportement.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Un individu dont le comportement rempli ces crit\u00e8res est clairement d\u00e9pendant, mais le risque ou la plainte de l\u2019entourage commence bien avant. L\u2019inqui\u00e9tude due aux cons\u00e9quences de la consommation est aussi fonction du type de produit ou de comportement et, \u00e9galement, des fins attendues. Par exemple, la boisson alcoolis\u00e9e peut \u00eatre consomm\u00e9e comme :<\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<p>\u2022 substance psychoactive, pour l\u2019influence sur l\u2019humeur ;<\/p>\n\n\n\n<p>\u2022 produit enivrant, pour s\u2019\u00e9vader de la r\u00e9alit\u00e9 ;<\/p>\n\n\n\n<p>\u2022 boisson, pour \u00e9tancher la soif ;<\/p>\n\n\n\n<p>\u2022 aliment, source de calories.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Elle peut aussi \u00eatre utilis\u00e9e pour sa valeur symbolique : selon la culture, la boisson alcoolis\u00e9e peut \u00eatre un symbole d\u2019inclusion ou d\u2019exclusion d\u2019un groupe social, un symbole de c\u00e9l\u00e9bration ou un acte sacramentel. Boire trois verres dans une situation conviviale semble moins inqui\u00e9tant que de les consommer pour se sentir moins triste. Mais, quelle que soit l\u2019utilisation de la <a href=\"https:\/\/monpsychomag.com\/index.php\/2021\/08\/30\/a-partir-de-quel-moment-la-consommation-dalcool-devient-pathologique\/\" data-type=\"post\" data-id=\"4579\"><strong>boisson<\/strong><\/a>, il n\u2019est pas possible d\u2019isoler une propri\u00e9t\u00e9 d\u2019une autre (OMS, 2006).<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Dans la plupart des cas, c\u2019est quand la consommation ou le comportement devient caract\u00e9ris\u00e9 que la question de la nuisance ou de la d\u00e9pendance se fait plus pressante. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Reprenant les recommandations de l\u2019OMS, un seuil est fond\u00e9 sur le crit\u00e8re de risque diff\u00e9r\u00e9 et cumulatif : 21 verres standard par semaine (soit trois verres par jour sans d\u00e9passer cinq verres par occasion) pour un homme et 14 verres standard (deux verres par jour sans d\u00e9passer cinq verres par occasion) pour une femme. Une personne qui consommerait plus pourrait constater dans le futur des probl\u00e8mes de sant\u00e9 avec un lien quelconque avec la consommation d\u2019alcool. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Une consommation au dessus de ce seuil peut \u00eatre nocive et constituer un risque imm\u00e9diat dans certaines circonstances, par exemple en cas de conduite automobile. Le risque varie donc en fonction du contexte et de nombreuses caract\u00e9ristiques du sujet : pathologies associ\u00e9es, modification de la tol\u00e9rance du consommateur, \u00e2ge, sexe, grossesse, \u00e9tats de fatigue, traitements m\u00e9dicamenteux\u2026<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong>L\u2019usage nocif<\/strong><em> <\/em>se concr\u00e9tise par la pr\u00e9sence de dommages physiques, psychiques et souvent sociaux li\u00e9es \u00e0 la consommation d\u2019alcool en l\u2019absence de crit\u00e8res d\u2019alcoolo-d\u00e9pendance.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong>L\u2019usage avec d\u00e9pendance<\/strong><em> <\/em>est caract\u00e9ris\u00e9 par la perte de la ma\u00eetrise de la consommation de la part du sujet, ind\u00e9pendamment des seuils de consommation et des dommages induits par celle-ci.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Aucun mode de consommation n\u2019est donc sans risque. Il a toujours un effet, plus ou moins perceptible, m\u00eame avec des quantit\u00e9s minimes. Continuer \u00e0 esp\u00e9rer qu\u2019il y ait une quantit\u00e9 <em><strong>normale<\/strong><\/em><em> <\/em>ou une consommation normale pour l\u2019alcool peut faire croire que le normal existe. Quoi qu\u2019il en soit, il ne peut pas y avoir une norme, la m\u00eame pour tous, dans la mesure o\u00f9 nous ne sommes pas \u00e9gaux devant les effets du produit.<\/p>\n\n\n\n<p><em style=\"\"><span><b>Vous avez des questions sur la <\/b><\/span><b>d\u00e9pendance a <\/b><\/em><strong><em>l&rsquo;alcool ?, et vous souhaitez en savoir plus ? N\u2019h\u00e9sitez pas \u00e0 poser votre question sur notre section \u00ab&nbsp;<a href=\"https:\/\/monpsychomag.com\/index.php\/monpsycho-jai-une-question\/\" data-type=\"page\" data-id=\"2451\">Questions<\/a>&nbsp;\u00bb . Et n\u2019oubliez pas de commenter l\u2019article pour expliquer votre point de vue sur le sujet, que vous viviez cette situation de pr\u00e8s ou de loin.<\/em><\/strong><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>La question pos\u00e9e fr\u00e9quemment par les consommateurs, ou leur entourage,<\/p>\n","protected":false},"author":122,"featured_media":4581,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[989],"tags":[990,397,682],"class_list":["post-4579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-addiction","tag-boisson","tag-dependance","tag-questions"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2021\/08\/alcool-e1630314652592.jpg?fit=800%2C502&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/4579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/122"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=4579"}],"version-history":[{"count":6,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/4579\/revisions"}],"predecessor-version":[{"id":4588,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/4579\/revisions\/4588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/4581"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=4579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=4579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=4579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}