{"id":406,"date":"2020-08-29T14:56:18","date_gmt":"2020-08-29T14:56:18","guid":{"rendered":"http:\/\/monpsychomag.com\/?p=406"},"modified":"2024-06-11T10:41:25","modified_gmt":"2024-06-11T10:41:25","slug":"les-bienfaits-davoir-une-estime-de-soi-forte","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2020\/08\/29\/les-bienfaits-davoir-une-estime-de-soi-forte\/","title":{"rendered":"Les bienfaits de l&rsquo;estime de soi"},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p class=\"has-text-align-justify\">Que nous faut-il pour \u00e9tablir des relations harmonieuses, vivre heureux et \u00eatre satisfait au travail? Une seule chose: une bonne dose d&rsquo;estime de soi. Le psychologue <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nathaniel_Branden\">Nathaniel Branden<\/a>, qui \u00e9tudie l&rsquo;estime de soi depuis plus de 30 ans, la d\u00e9finit comme \u00ab le jugement que nous portons sur nous m\u00eame \u00bb. En fait, l&rsquo;estime de soi est la capacit\u00e9 de se respecter et de s&rsquo;aimer. Et pour y arriver, il faut croire en nos comp\u00e9tences, en notre int\u00e9grit\u00e9, en notre valeur et en notre capacit\u00e9 d&rsquo;\u00eatre aim\u00e9e.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><br>Lorsque nous sommes attaqu\u00e9s, on accepte plus facilement les critiques, on d\u00e9fend ce qui nous tient \u00e0 c\u0153ur et on atteint les objectifs qu&rsquo;on s&rsquo;est fix\u00e9 en cas d&rsquo;une estime de soi forte. D&rsquo;un autre c\u00f4t\u00e9, si on a une pi\u00e8tre opinion de nous m\u00eame, cela influence directement notre vie: on a l&rsquo;impression de passer \u00e0 c\u00f4t\u00e9 de tout et de ne pas \u00eatre aim\u00e9e.<\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<p class=\"has-text-align-justify\"><br>Mais attention, <a href=\"https:\/\/monpsychomag.com\/index.php\/produit\/resultat-test-destime-de-soi\/\"><strong>l&rsquo;estime de soi<\/strong><\/a> n&rsquo;est pas une panac\u00e9e! M\u00eame les personnes qui ont confiance en elles, rencontrent des difficult\u00e9s. \u00c0 la diff\u00e9rence que, quand cela leur arrive, elles sont mieux arm\u00e9es et savent trouver en elles les ressources pour composer avec la situation. En cas de difficult\u00e9, <strong><a href=\"https:\/\/monpsychomag.com\/index.php\/rendez-vous\/\" data-type=\"page\" data-id=\"6193\">consultez un sp\u00e9cialiste pour recevoir de l&rsquo;aide<\/a><\/strong>.<\/p>\n\n\n\n<p>Soyons positifs, et trouvons le meilleur en toutes choses.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Que nous faut-il pour \u00e9tablir des relations harmonieuses, vivre heureux et \u00eatre satisfait au travail? Une seule chose: une bonne dose d&rsquo;estime de soi. Le psychologue&#8230;<\/p>\n","protected":false},"author":127,"featured_media":410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[167],"class_list":["post-406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bon-a-savoir","tag-nathaniel-branden"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2020\/08\/Resizer_15987380507970-1.jpg?fit=800%2C533&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=406"}],"version-history":[{"count":6,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/406\/revisions"}],"predecessor-version":[{"id":8343,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/406\/revisions\/8343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/410"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}