{"id":3940,"date":"2021-07-28T23:29:17","date_gmt":"2021-07-28T23:29:17","guid":{"rendered":"http:\/\/monpsychomag.com\/?p=3940"},"modified":"2021-07-30T20:27:37","modified_gmt":"2021-07-30T20:27:37","slug":"differenciation-des-types-dintelligence","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2021\/07\/28\/differenciation-des-types-dintelligence\/","title":{"rendered":"Diff\u00e9renciation des types d&rsquo;intelligence"},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p class=\"has-text-align-justify\">Traiter la question de la diff\u00e9renciation des <a href=\"https:\/\/monpsychomag.com\/index.php\/2021\/07\/22\/il-existe-8-types-dintelligence-decouvrez-le-votre-ici\/\" data-type=\"post\" data-id=\"3787\"><strong>types d&rsquo;intelligence<\/strong><\/a> en fonction des caract\u00e9ristiques de l&rsquo;environnement social d&rsquo;un individu revient \u00e0 traiter la question suivante : <em>Comment l&rsquo;environnement impacte l&rsquo;intelligence de l&rsquo;enfant ?<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Dans l&rsquo;article sur les <a href=\"https:\/\/monpsychomag.com\/index.php\/2021\/07\/22\/il-existe-8-types-dintelligence-decouvrez-le-votre-ici\/\" data-type=\"post\" data-id=\"3787\"><strong>types d&rsquo;intelligence<\/strong><\/a>, nous avions identifi\u00e9s un peu plus de 08 types d&rsquo;intelligence soit 09 selon d&rsquo;autres travaux r\u00e9cents du <em>Psychologue Howard Gardner<\/em>. Devant les faits, la recherche nous ram\u00e8ne au choix d&rsquo;une \u00e9tude longitudinale pour mieux comprendre les d\u00e9terminants d&rsquo;un type d&rsquo;intelligence par rapport \u00e0 d&rsquo;autres types en fonction des facteurs environnementaux au sein de la cellule familiale. <em>Dans le cochon familial, quels sont les facteurs qui influencent le d\u00e9veloppement des intelligences?<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Des recherches port\u00e9es sur la connaissance et la ma\u00eetrise des m\u00e9canismes sous-jacent et les d\u00e9terminants de l&rsquo;intelligence ont souvent \u00e9t\u00e9 des \u00e9tudes longitudinales caract\u00e9ristiques de la formation de cohortes faisant l&rsquo;objet de recherches et d\u00e9terminant les donn\u00e9es objectives. <em>Franck Ramus et ses coll\u00e8gues<\/em>, mettent un lien de fa\u00e7on assez fin entre <em>les facteurs environnementaux et le d\u00e9veloppement cognitif de l&rsquo;enfant<\/em>. Il d\u00e9montre que certains aspects <em>dits modifiables<\/em> de l&rsquo;environnement ou des soins re\u00e7us par l&rsquo;enfant ont un impact sur l&rsquo;\u00e9volution de son cerveau. <\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<p class=\"has-text-align-justify\">La recherche men\u00e9e conjointement par le Laboratoire de <a href=\"https:\/\/www.usabilis.com\/definition-sciences-cognitives\/\"><strong>Sciences cognitives<\/strong><\/a> et Psycholinguistique, s&rsquo;est int\u00e9ress\u00e9e aux effets diff\u00e9rentiels des facteurs analys\u00e9s ( Poids de naissance, dur\u00e9e de l&rsquo;allaitement ou niveau de revenus, entre autres) sur plusieurs dimensions de l&rsquo;intelligence, telles que les comp\u00e9tences verbales (phonologie, compr\u00e9hension. Vocabulaire, capacit\u00e9s conceptuelles, m\u00e9moire \u00e0 court terme) et non verbales ( perception visuelle, coordination visio-motrice, capacit\u00e9 d&rsquo;abstraction et de cat\u00e9gorisation, calcul). <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Nous distinguons deux types d&rsquo;items. Les facteurs distaux assez g\u00e9n\u00e9raux dont on sait leur impact global sur le d\u00e9veloppement de l&rsquo;enfant tels que le niveau d&rsquo;\u00e9ducation des parents. Et les facteurs proximaux qui ont leur impact plus direct sur l&rsquo;enfant et constituent en quelques sorte le moyen par lequel les facteurs distaux influencent le d\u00e9veloppement des diff\u00e9rentes facettes. Il est d\u00e9montre le r\u00f4le pr\u00e9pond\u00e9rant d&rsquo;un environnement stimulant faisant \u00e9tat d&rsquo;une corr\u00e9lation entre ces diff\u00e9rents \u00e9l\u00e9ments, les <a href=\"https:\/\/fr.chalized.com\/liste-des-competences-en-communication-verbale\/\"><strong>comp\u00e9tences verbales<\/strong><\/a> et non verbales des enfants.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em><strong>Vous avez des questions sur cet article, et vous souhaitez en savoir plus ? Posez votre question sur notre section&nbsp;<\/strong><a href=\"https:\/\/monpsychomag.com\/index.php\/monpsycho-jai-une-question\/\">\u00ab <strong>Questions<\/strong> \u00bb<\/a><strong>&nbsp;.<\/strong><\/em><strong><em> Et n\u2019oubliez pas de commenter l\u2019article pour expliquer votre point de vue sur le sujet.<\/em><\/strong><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Traiter la question de la diff\u00e9renciation des types d&rsquo;intelligence en<\/p>\n","protected":false},"author":128,"featured_media":3945,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[353],"tags":[891,682,892,890],"class_list":["post-3940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-connaissance-de-soi-et-des-autres","tag-competences-verbales","tag-questions","tag-sciences-cognitives","tag-types-dintelligence"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2021\/07\/intelligence-e1627549804209.jpg?fit=800%2C534&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/128"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=3940"}],"version-history":[{"count":5,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3940\/revisions"}],"predecessor-version":[{"id":3976,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3940\/revisions\/3976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/3945"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=3940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=3940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=3940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}