{"id":3789,"date":"2021-07-22T10:18:31","date_gmt":"2021-07-22T10:18:31","guid":{"rendered":"http:\/\/monpsychomag.com\/?p=3789"},"modified":"2021-07-22T10:53:29","modified_gmt":"2021-07-22T10:53:29","slug":"psychologie-du-sport-et-motivation-partie-1","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2021\/07\/22\/psychologie-du-sport-et-motivation-partie-1\/","title":{"rendered":"Psychologie du sport et motivation : Partie 1"},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p class=\"has-text-align-justify\">Qui ne s\u2019est jamais retrouv\u00e9 \u00e0 faire des <a href=\"https:\/\/monpsychomag.com\/index.php\/2021\/07\/05\/quest-ce-que-lengagement-organisationnel\/\" data-type=\"post\" data-id=\"3185\"><strong>engagements<\/strong><\/a> et \u00e0 ne pas les honorer au bout de quelques jours\/ semaines ? \u00c7a commence tr\u00e8s souvent \u00e0 la fin de l\u2019ann\u00e9e o\u00f9 on se dit qu&rsquo; au d\u00e9but de l\u2019ann\u00e9e suivante, on va d\u00e9buter de nouvelles activit\u00e9s ( des fois c\u2019est l\u2019abonnement pour des cours de natation, l\u2019abonnement \u00e0 la salle de musculation ou un nouveau r\u00e9gime alimentaire pour perdre quelques kilos\u2026) mais au bout de quelques jours ou quelques semaines, \u201cpfff\u201d tout tombe \u00e0 l\u2019eau: il y a une perte de motivation. Les grands sportifs aussi sont confront\u00e9s durant leur carri\u00e8re \u00e0 ce ph\u00e9nom\u00e8ne de perte de motivation, mais aujourd\u2019hui sans plus tarder nous allons comprendre ce qui en est la cause<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cause biologique<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\"><a href=\"https:\/\/www.bordeaux-neurocampus.fr\/staff\/francis-chaouloff\/\"><strong>Francis Chaouloff<\/strong><\/a>, directeur de recherche Inserm au NeuroCentre Magendie \u00e0 l\u2019Universit\u00e9 Bordeaux S\u00e9galen, Sarah Dubreucq, \u00e9tudiante en Th\u00e8se, et Fran\u00e7ois Georges, charg\u00e9 de recherche CNRS \u00e0 l\u2019Institut Interdisciplinaire de Neurosciences \u00e0 l\u2019Universit\u00e9 Bordeaux S\u00e9galen, ont d\u00e9couvert qu\u2019une prot\u00e9ine, le r\u00e9cepteur des cannabino\u00efdes CB1, joue un r\u00f4le cl\u00e9 lors de l\u2019exercice physique. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Les r\u00e9sultats sont parus dans la revue Biological Psychiatry. En faisant une \u00e9tude sur des souris, les chercheurs ont constat\u00e9 que l\u2019emplacement de ce r\u00e9cepteur dans la r\u00e9gion du cerveau associ\u00e9e \u00e0 la motivation et au syst\u00e8me de r\u00e9compense commande la r\u00e9alisation d\u2019un <strong><a href=\"http:\/\/dictionnaire.sensagent.leparisien.fr\/exercice%20physique\/fr-fr\/#:~:text=L%27%20exercice%20physique%20est%20une%20activit%C3%A9%20physique%20pratiqu%C3%A9e,d%27%C3%A9ducation%2C%20il%20est%20le%20pendant%20des%20exercices%20intellectuels.\">exercice physique<\/a><\/strong> volontaire. Sur les souris, l\u2019absence de ce r\u00e9cepteur CB1 a fait baisser de 20 \u00e0 30 % leur niveau d\u2019exercice alors qu\u2019elles avaient acc\u00e8s \u00e0 une roue 3 heures par jour L&rsquo;incapacit\u00e9 \u00e0 ressentir du plaisir lors de l&rsquo;activit\u00e9 physique, souvent cit\u00e9e comme une cause de non adh\u00e9sion partielle ou totale \u00e0 un programme d&rsquo;exercice physique. <\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les facteurs internes<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\">\u2022 Votre &lt;&lt;volont\u00e9&gt;&gt; de faire n\u2019est pas assez puissante. Lorsque votre envie, votre volont\u00e9 de r\u00e9aliser une t\u00e2che, d\u2019atteindre un objectif n\u2019est pas assez puissante, au premier obstacle il est fort probable que votre motivation chute compl\u00e8tement.<br> <br>\u2022 Le manque de dynamisme, de vibrations  pendant l\u2019ex\u00e9cution de  l\u2019activit\u00e9 que vous menez. Si l\u2019activit\u00e9 en question ne  bouscule pas un tout petit peu vos \u00e9motions vos pens\u00e9es et votre comportement ( ne vous procure pas de plaisir\u2026) cela peut conduire \u00e0 une perte de motivation.<br> <br>\u2022 La <strong>mauvaise routine<\/strong>  c\u2019est lorsque que vous avez l\u2019impression de tout le temps faire la m\u00eame chose sans rien apprendre de nouveau et sans aucune \u00e9volution.<br> <br>\u2022 L\u2019impression de ne pas \u00e9voluer assez vite ou pas du tout. Les r\u00e9sultats auxquels vous vous attendiez n\u2019apparaissent pas \u00e0 la fr\u00e9quence que vous souhaitez, cela agis sur votre estime et votre confiance en vous qui diminuent et peut conduire \u00e0 une perte de motivation. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Facteurs en lien avec le contexte<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\">\u2022 Vous vous comparez aux autres et vous avez tendance \u00e0 minimiser ce que vous faites, vos progr\u00e8s.<br> <br>\u2022 Votre objectif de d\u00e9part est trop \u00e9lev\u00e9 par rapport aux moyens dont vous disposez<br> <br>\u2022 Difficult\u00e9 \u00e0 organiser votre emploi du temps et \u00e0 prioriser vos t\u00e2ches <br> <br>Nb : il existe 2 types de motivation, la motivation \u201c intrins\u00e8que \u201d et la motivation \u201c extrins\u00e8que \u201d nous allons plus le d\u00e9velopper dans la partie 2 restez branch\u00e9s .<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Nous sommes \u00e0 la fin de cette premi\u00e8re partie sur la motivation et le sport, en attendant la seconde partie, dites-vous en commentaire comment vous vous g\u00e9rer la perte de motivation. <br><br>Vous avez des questions sur la Psychologie du sport et la motivation, et vous souhaitez en savoir plus ? posez votre question sur notre section \u00ab <strong><a href=\"https:\/\/monpsychomag.com\/index.php\/monpsycho-jai-une-question\/\" data-type=\"page\" data-id=\"2451\">Questions<\/a><\/strong> \u00bb . Et n\u2019oubliez pas de commenter l\u2019article pour expliquer votre point de vue.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Qui ne s\u2019est jamais retrouv\u00e9 \u00e0 faire des engagements et<\/p>\n","protected":false},"author":139,"featured_media":3788,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[593],"tags":[862,863,861,682],"class_list":["post-3789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-psychologie-du-sport","tag-engagements","tag-exercice-physique","tag-francis-chaouloff","tag-questions"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2021\/07\/Screenshot_20210722-101953-e1626950685366.png?fit=720%2C364&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=3789"}],"version-history":[{"count":4,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3789\/revisions"}],"predecessor-version":[{"id":3796,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3789\/revisions\/3796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/3788"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=3789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=3789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=3789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}