{"id":3596,"date":"2021-07-22T20:23:11","date_gmt":"2021-07-22T20:23:11","guid":{"rendered":"http:\/\/monpsychomag.com\/?p=3596"},"modified":"2021-07-23T06:40:35","modified_gmt":"2021-07-23T06:40:35","slug":"violences-psychologiques-au-travail","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2021\/07\/22\/violences-psychologiques-au-travail\/","title":{"rendered":"Violences psychologiques au travail"},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p class=\"has-text-align-justify\">Hello chers lecteurs. Je vous esp\u00e8re en forme. Bienvenus dans ce nouveau num\u00e9ro o\u00f9 <a href=\"https:\/\/monpsychomag.com\/index.php\/2021\/07\/08\/violences-physiques-au-travail\/\" data-type=\"post\" data-id=\"3182\"><span class=\"has-inline-color has-luminous-vivid-orange-color\"><strong>comme promis<\/strong><\/span><\/a> nous allons parler des violences psychologiques au travail. Pr\u00e9c\u00e9demment je vous avais parl\u00e9 des<a href=\"https:\/\/monpsychomag.com\/index.php\/2021\/07\/08\/violences-physiques-au-travail\/\" data-type=\"post\" data-id=\"3182\"> <span class=\"has-inline-color has-luminous-vivid-orange-color\"><strong>violences physiques en entreprise<\/strong><\/span><\/a> et nous avions vu qu&rsquo;elles engendrent elles-m\u00eames les violences psychologiques.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qu&rsquo;entend t-on par violence psychologique ?<\/h3>\n\n\n\n<p class=\"has-text-align-justify\">On appelle risque psychologique tout risque ou toute situation qui d\u00e9range l&rsquo;\u00e9quilibre psychologique du travailleur. Par extension, les risques psychosociaux (RPS) correspondent \u00e0 des situations de travail o\u00f9 sont pr\u00e9sents, combin\u00e9s ou non\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>du stress&nbsp;: d\u00e9s\u00e9quilibre entre la perception qu\u2019une personne a des contraintes de son environnement de travail et la perception qu\u2019elle a de ses propres ressources pour y faire face&nbsp;;<\/li><li>des violences internes commises au sein de l\u2019entreprise par des salari\u00e9s&nbsp;: harc\u00e8lement moral ou sexuel, conflits exacerb\u00e9s entre des personnes ou entre des \u00e9quipes&nbsp;;<\/li><li>des violences externes commises sur des salari\u00e9s par des personnes externes \u00e0 l\u2019entreprise (insultes, menaces, agressions\u2026) ?<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Quels sont les facteurs de violence psychologique au travail ?<\/h3>\n\n\n\n<p>Certaines situations parmi tant d&rsquo;autres peuvent favoriser les violences psychologiques. Entre autres nous avons:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Intensit\u00e9 et temps de travail<\/h4>\n\n\n\n<p class=\"has-text-align-justify\">Cette premi\u00e8re cat\u00e9gorie comprend les notions d\u2019\u00ab&nbsp;exigences psychologiques&nbsp;\u00bb (voir mod\u00e8le de Karasek) et \u00ab&nbsp;d\u2019efforts&nbsp;\u00bb <a href=\"https:\/\/www.cairn.info\/risques-psychosociaux-et-qualite-de-vie-au-travail--9782100781447-page-113.html\" data-type=\"URL\" data-id=\"https:\/\/www.cairn.info\/risques-psychosociaux-et-qualite-de-vie-au-travail--9782100781447-page-113.html\">(<span class=\"has-inline-color has-luminous-vivid-orange-color\">voir mod\u00e8le de Siegrist<\/span>)<\/a> mais plus largement les contraintes de rythme, l\u2019existence d\u2019objectifs irr\u00e9alistes ou flous, l\u2019exigence de polyvalence non ma\u00eetris\u00e9e, les instructions contradictoires, les longues journ\u00e9es de travail, le travail en horaires atypiques, l\u2019impr\u00e9visibilit\u00e9 des horaires de travail\u2026<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Exigences \u00e9motionnelles<\/h4>\n\n\n\n<p class=\"has-text-align-justify\">Les exigences \u00e9motionnelles font r\u00e9f\u00e9rence \u00e0 la n\u00e9cessit\u00e9 de ma\u00eetriser et fa\u00e7onner ses propres \u00e9motions. Elles concernent essentiellement les m\u00e9tiers de services&nbsp;: exigence de sourire ou de bonne humeur, tensions avec le public, contact avec la souffrance ou la d\u00e9tresse humaine. L\u2019exigence de devoir cacher ses \u00e9motions peut \u00e9galement concerner d\u2019autres secteurs d\u2019activit\u00e9s quand la culture dominante de l\u2019entreprise est le contr\u00f4le total de soi en toutes circonstances et l\u2019affichage constant d\u2019une \u00ab&nbsp;attitude positive&nbsp;\u00bb.<\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<h4 class=\"wp-block-heading\">Manque d\u2019autonomie<\/h4>\n\n\n\n<p class=\"has-text-align-justify\">L\u2019autonomie au travail d\u00e9signe la possibilit\u00e9 d\u2019\u00eatre acteur dans son travail. Elle rejoint la notion de \u00ab\u00a0latitude d\u00e9cisionnelle\u00a0\u00bb\u00a0\u00bb (voir mod\u00e8le \u00ab\u00a0job strain\u00a0\u00bb de Karasek) et inclut non seulement les marges de man\u0153uvre (la possibilit\u00e9 de s\u2019auto-organiser dans son travail) mais \u00e9galement la participation aux d\u00e9cisions qui concernent directement son activit\u00e9 ainsi que l\u2019utilisation et le d\u00e9veloppement de ses comp\u00e9tences.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Vous vous demandez surement depuis tout \u00e0 l&rsquo;heure ce que c&rsquo;est le mod\u00e8le de Karasek et qui est Karasek. Eh bien, le questionnaire de Karasek, du nom de son principal initiateur, un sociologue nord-am\u00e9ricain qui a travaill\u00e9 sur la tension au travail, est un outil internationalement utilis\u00e9 pour d\u00e9crire les facteurs de risques psychosociaux au travail. Ce questionnaire \u00e9value trois dimensions de l\u2019environnement psychosocial au travail : la demande psychologique, la latitude d\u00e9cisionnelle et le soutien social.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les cons\u00e9quences des violences psychologiques au travail<\/h3>\n\n\n\n<p class=\"has-text-align-justify\">Comme vous vous en doutez, la cons\u00e9quence imm\u00e9diate des violences psychologiques au travail est l&rsquo;incapacit\u00e9 du travailleur \u00e0 fournir un rendement optimal. Outre cela, les violences psychosociaux sont souvent r\u00e9sum\u00e9s en stress au travail, stress qui engendre \u00e0 son tour des maladies cardio-vasculaires, l&rsquo;anxi\u00e9t\u00e9, la d\u00e9pression, l&rsquo;\u00e9puisement professionnel, voire le suicide. Esp\u00e9rant ne pas en arriver l\u00e0, le psychologue du travail doubl\u00e9 par le m\u00e9decin du travail ont pour r\u00f4le de veille \u00e0 ce que les risques de violences psychologiques soient \u00e9touff\u00e9s dans leur \u0153uf afin de garantir un environnement de travail stable et ad\u00e9quat pour un bonne \u00e9volution de l&rsquo;entreprise. N\u00e9anmoins, il serait judicieux en tant que travailleur de <a href=\"https:\/\/monpsychomag.com\/index.php\/2021\/07\/13\/comment-gerer-son-stress-au-travail\/\" data-type=\"post\" data-id=\"3499\"><span class=\"has-inline-color has-luminous-vivid-orange-color\">pr\u00e9venir le stress au travail. <\/span><\/a><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em><strong>Nous voici<\/strong> <strong>\u00e0 la fin de ce num\u00e9ro, j\u2019esp\u00e8re que \u00e7a vous a plu. Vous \u00eates victime de violences psychologiques au travail, ou vous n&rsquo;arrivez tout simplement pas \u00e0 g\u00e9rer votre stress ?<a href=\"https:\/\/monpsychomag.com\/index.php\/contact-us\/\" data-type=\"page\" data-id=\"64\"> <span class=\"has-inline-color has-luminous-vivid-orange-color\">Demandez gratuitement une consultation aupr\u00e8s d\u2019un sp\u00e9cialiste de notre magazine africain de psychologie<\/span><\/a> ou posez votre question sur notre section <a href=\"https:\/\/monpsychomag.com\/index.php\/monpsycho-jai-une-question\/\" data-type=\"page\" data-id=\"2451\"><span class=\"has-inline-color has-luminous-vivid-orange-color\">\u00ab Questions \u00bb<\/span><\/a> . Et n\u2019oubliez pas de commenter l\u2019article pour expliquer votre point de vue sur le sujet, que vous viviez cette situation de pr\u00e8s ou de loin.<\/strong><\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Hello chers lecteurs. Je vous esp\u00e8re en forme. Bienvenus dans<\/p>\n","protected":false},"author":129,"featured_media":3810,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[404],"tags":[800,867,346,869,868],"class_list":["post-3596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-travail","tag-entreprise","tag-risques-psychologiques","tag-travail","tag-violence-autravail","tag-violences-psychologiques"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2021\/07\/pexels-yan-krukov-7640470-scaled.jpg?fit=2560%2C1707&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=3596"}],"version-history":[{"count":3,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3596\/revisions"}],"predecessor-version":[{"id":3815,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3596\/revisions\/3815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/3810"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=3596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=3596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=3596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}