{"id":345,"date":"2020-07-28T19:48:30","date_gmt":"2020-07-28T19:48:30","guid":{"rendered":"http:\/\/monpsychomag.com\/?p=345"},"modified":"2020-09-03T12:40:06","modified_gmt":"2020-09-03T12:40:06","slug":"mon-amie-couche-avec-mon-homme","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2020\/07\/28\/mon-amie-couche-avec-mon-homme\/","title":{"rendered":"Mon amie couche avec mon homme depuis deux ans"},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p>Je sors avec mon mec il y a de cela 6 ans. J&rsquo;\u00e9tais bien avec la famille, et j\u2019avais deux copines avec qui j\u2019\u00e9tais comme des s\u0153urs. Apr\u00e8s quelques ann\u00e9es, il y eu des altercations entre une de mes copines et moi. Finalement, on n&rsquo;\u00e9tait plus ensemble. Elle est devenue la meilleure pote de ma <a href=\"https:\/\/r.search.yahoo.com\/_ylt=AwrJS5XQfCBf6zwA_H4k24lQ;_ylu=X3oDMTE0aXNuajExBGNvbG8DaXIyBHBvcwMxBHZ0aWQDVUlGUkMwMV8xBHNlYwNzcg--\/RV=2\/RE=1595993425\/RO=10\/RU=https%3a%2f%2fwww.linternaute.fr%2fdictionnaire%2ffr%2fdefinition%2fbelle-soeur%2f\/RK=2\/RS=9YliDt0x.Njod.cmjqIcp4GdLNY-\">belle-s\u0153ur<\/a>. Suite \u00e0 \u00e7a, ma belle-s\u0153ur a commenc\u00e9 \u00e0 me d\u00e9tester m\u2019insulter, et autre !! Du coup, j\u2019ai compris que s\u00fbrement, ma copine est all\u00e9 lui raconter des trucs sales sur moi et des b\u00eatises qu\u2019on a eu \u00e0 faire et tous.<\/p>\n\n\n\n<p>Mon petit ami a voyag\u00e9 sur 2 ans et durant ce temps, rien n\u2019\u00e9tait plus s\u00e9rieux entre nous. On ne s&rsquo;est pas dit que c&rsquo;est fini, mais il \u00e9tait distant et verbalement m\u00e9chant envers moi. Alors, je me suis fait une vie \u00e0 moi pour m\u2019en sortir. Durant tout ce temps, j\u2019\u00e9tais toujours ami avec son fr\u00e8re. Il \u00e9tait au courant de tout \u00e0 propos de moi. Il conna\u00eet m\u00eame le mec avec qui j\u2019entreprends des relations.<\/p>\n\n\n\n<p>Apres quelques temps, mon mec \u00e9tait rentr\u00e9 et deux mois avant qu\u2019il ne rentre il ne se passait plus rien entre l\u2019autre mec et moi puisque je lui ai dit que je vais donner une chance \u00e0 mon couple. Quand mon mec qui a voyag\u00e9 est de retour, tout a bien repris. Mais je ne lui ai pas fait savoir mon <a href=\"https:\/\/r.search.yahoo.com\/_ylt=AwrJS9NMfSBfhHgAlF8k24lQ;_ylu=X3oDMTE0N2RhdDJ0BGNvbG8DaXIyBHBvcwMzBHZ0aWQDVUlGUkMwMV8xBHNlYwNzcg--\/RV=2\/RE=1595993549\/RO=10\/RU=https%3a%2f%2flivre.fnac.com%2fa4117536%2fJean-Francois-Vezina-L-aventure-amoureuse\/RK=2\/RS=nXcZYwdcxXpPSyQF7qpBTHgNzqE-\">aventure<\/a>.<\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<p>Apres, j\u2019ai appris que le gar\u00e7on avec qui j\u2019ai eu l\u2019aventure couchait avec moi et ma vraie copine quand on \u00e9tait ensemble. Cette copine \u00e9tait comme une s\u0153ur pour moi. J\u2019\u00e9tais tellement boulevers\u00e9e et choqu\u00e9e que je ne voulais plus les voir dans nos rayons.<\/p>\n\n\n\n<p>Un beau matin, le petit fr\u00e8re de mon mec devient ami avec mon ex. Arriv\u00e9 \u00e0 un moment o\u00f9 leur amiti\u00e9 devient plus intime et intense, j\u2019ai fait savoir \u00e0 mon mec l\u2019aventure que j\u2019ai eu.<\/p>\n\n\n\n<p>Aujourd\u2019hui, mon histoire d\u2019amour se transforme en cauchemar inimaginable. Je suis atteint sur le plan <a href=\"https:\/\/r.search.yahoo.com\/_ylt=AwrJQ5ryfSBfVjgAd3kk24lQ;_ylu=X3oDMTE0aXNuajExBGNvbG8DaXIyBHBvcwMxBHZ0aWQDVUlGUkMwMV8xBHNlYwNzcg--\/RV=2\/RE=1595993715\/RO=10\/RU=https%3a%2f%2fwww.linternaute.fr%2fdictionnaire%2ffr%2fdefinition%2fpsychologique%2f\/RK=2\/RS=v2ZjjVtF6iLiynGr4Rd0jRwoEzs-\">psychologique<\/a>. Mon <a href=\"https:\/\/r.search.yahoo.com\/_ylt=AwrJQ5yAfSBfkgQAgAck24lQ;_ylu=X3oDMTE0aXNuajExBGNvbG8DaXIyBHBvcwMxBHZ0aWQDVUlGUkMwMV8xBHNlYwNzcg--\/RV=2\/RE=1595993600\/RO=10\/RU=https%3a%2f%2fwww.linternaute.fr%2fdictionnaire%2ffr%2fdefinition%2fbeau-frere%2f\/RK=2\/RS=Jgpaa1W7HwwEjlwGqepDO5OOVOk-\">beau-fr\u00e8re<\/a> ne me parle plus, mon amie a envoy\u00e9 nos messages dans lesquels je lui parlais de mes <a href=\"https:\/\/r.search.yahoo.com\/_ylt=AwrP4lA6fiBfYgIAPwMk24lQ;_ylu=X3oDMTE0N2RhdDJ0BGNvbG8DaXIyBHBvcwMzBHZ0aWQDVUlGUkMwMV8xBHNlYwNzcg--\/RV=2\/RE=1595993787\/RO=10\/RU=http%3a%2f%2fdictionnaire.sensagent.leparisien.fr%2f%25C3%25A9bats%2ffr-fr%2f\/RK=2\/RS=A3pxA6DshS2v9ftbNKIjCtaEVOU-\">\u00e9bats<\/a>, \u00e0 d\u2019autres hommes. Ma vie priv\u00e9e passe de bouche \u00e0 oreille.<\/p>\n\n\n\n<p>Ma belle famille me rejette, mon mec est distant, hors je l&rsquo;aime.<br>Maintenant je peux dire que je n\u2019ai m\u00eame pas de moyen pour me d\u00e9fendre et je suis au milieu de cette temp\u00eate sans issue de secours.<\/p>\n\n\n\n<p>Que faire Aidez-moi svp je suis perdue.<\/p>\n\n\n\n<p><strong>Ceci est une histoire r\u00e9elle d&rsquo;une internaute anonyme<\/strong><\/p>\n\n\n\n<p><em>Veuillez partager en commentaire vos avis et conseils \u00e0 l\u2019internaute.<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Je sors avec mon mec il y a de cela 6 ans. J&rsquo;\u00e9tais bien avec la famille, et j\u2019avais deux copines avec qui j\u2019\u00e9tais comme des s\u0153urs. Apr\u00e8s quelques ann\u00e9es&#8230;<\/p>\n","protected":false},"author":2,"featured_media":346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[67],"tags":[132,130,133,131],"class_list":["post-345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire-de-lanonyme","tag-beau-frere","tag-belle-soeur","tag-ebats","tag-psychologique"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2020\/07\/cccccccc.......jpg?fit=800%2C533&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=345"}],"version-history":[{"count":3,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/345\/revisions"}],"predecessor-version":[{"id":459,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/345\/revisions\/459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/346"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}