{"id":3203,"date":"2021-07-06T09:49:25","date_gmt":"2021-07-06T09:49:25","guid":{"rendered":"http:\/\/monpsychomag.com\/?p=3203"},"modified":"2021-07-06T15:36:59","modified_gmt":"2021-07-06T15:36:59","slug":"quand-doit-on-parler-de-sexualite-a-un-adolescent","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2021\/07\/06\/quand-doit-on-parler-de-sexualite-a-un-adolescent\/","title":{"rendered":"Quand doit-on parler de sexualit\u00e9 \u00e0 un adolescent ?"},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p class=\"has-text-align-justify\">Heureux de vous retrouver encore dans ce nouveau num\u00e9ro autour des sujets d&rsquo;<a href=\"https:\/\/monpsychomag.com\/index.php\/category\/education\/\"><strong>\u00e9ducation<\/strong><\/a>. Pr\u00e9c\u00e9demment, nous avons parl\u00e9 de l&rsquo;\u00e9ducation de l&rsquo;adolescent de fa\u00e7on g\u00e9n\u00e9rale. Aujourd&rsquo;hui, nous allons revenir sur un aspect int\u00e9ressant : l&rsquo;\u00e9ducation sexuelle de l&rsquo;adolescent. A quel \u00e2ge doit-on en parler \u00e0 l&rsquo;adolescent ? Qui doit en parler ? \u00c9ducateurs, parents, je suis <a href=\"https:\/\/monpsychomag.com\/index.php\/author\/yaomarc\/\"><strong>Marc EFAVI<\/strong><\/a>, apr\u00e8s ma formation en psychologie de l&rsquo;\u00e9ducation, je suis actuellement r\u00e9dacteur sur votre <a href=\"https:\/\/monpsychomag.com\/index.php\/je-veux-mabonner-a-monpsychoag\/\"><strong>magazine africain de psychologie<\/strong><\/a>, je vous propose des solutions face aux probl\u00e8mes d&rsquo;\u00e9ducation. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">L\u2019adolescence  est  marqu\u00e9e  par  l\u2019\u00e9veil  de  la  <a href=\"https:\/\/monpsychomag.com\/index.php\/2020\/07\/02\/cest-quoi-reellement-la-sexualite\/\" data-type=\"post\" data-id=\"191\"><strong>sexualit\u00e9<\/strong><\/a>.  On  dit  que  l\u2019instinct  sexuel monte brutalement \u00e0 la surface. Cela est d\u00fb aux diff\u00e9rentes transformations physiologiques qui surviennent au d\u00e9but de l&rsquo;adolescence (entr\u00e9e en activit\u00e9 des glandes g\u00e9nitales, le mod\u00e8le adulte des formes corporelles, etc. A quel \u00e2ge faut-il aborder les probl\u00e8mes sexuels ? Les adolescents souffrent en r\u00e8gle g\u00e9n\u00e9rale d\u2019un manque d\u2019informations. Il est imp\u00e9rieux que celles-ci leur soient donn\u00e9es d\u00e8s la pubert\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Chez les filles<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\">Pour  les  filles,  les  premi\u00e8res  r\u00e8gles  fournissent  une  excellente  occasion  de  dialoguer  sur  la sexualit\u00e9.  Les  m\u00e8res  ne  devraient  pas  se  d\u00e9rober  \u00e0  cette  t\u00e2che.  Trop  souvent  cependant,  les explications donn\u00e9es sont trop sommaires et peuvent, au lieu d\u2019\u00e9clairer, induire en erreur.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Chez les gar\u00e7ons<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\">Du c\u00f4t\u00e9 des gar\u00e7ons, les cours pr\u00e9liminaires sur l\u2019anatomie et la physiologie de la sexualit\u00e9 devraient \u00eatre suivis d\u00e8s les premiers signes de la pubert\u00e9, c\u2019est-\u00e0-dire entre 10 et 13 ans. Il est important que l\u2019information physiologique se fonde sur les manifestations de la g\u00e9nitalit\u00e9 propres  \u00e0  la  pubert\u00e9.  Les  signes  secondaires  de  la  sexualit\u00e9  doivent  faire  l\u2019objet  d\u2019une explication pr\u00e9cise : pilosit\u00e9, seins, mue de la voix. Puis doivent \u00eatre expliqu\u00e9s les ph\u00e9nom\u00e8nes sexuels  proprement  dits  :  menstruations  chez  les  filles,  \u00e9jaculations  spontan\u00e9es  diurnes  ou nocturnes chez les gar\u00e7ons. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Utilisez un vocabulaire clair et pr\u00e9cis<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\"><strong>Les r\u00e8gles<\/strong> : \u00ab chaque mois (quinze jours avant les r\u00e8gles), un petit \u0153uf est pondu par un des ovaires dans la poche faite pour recevoir le b\u00e9b\u00e9 : l\u2019ut\u00e9rus. Cette poche se gonfle et le sang afflue vers elle, pr\u00eat \u00e0 nourrir le b\u00e9b\u00e9 qui pourrait se former si l\u2019\u0153uf compl\u00e9mentaire venait rejoindre celui pondu par l\u2019ovaire. Lorsqu\u2019il ne vient pas, l\u2019\u0153uf inutilis\u00e9 et le sang sont rejet\u00e9s \u00bb. <\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<p class=\"has-text-align-justify\"><strong>Ejaculations<\/strong> : \u00ab les \u00e9jaculations sont normales. Le liquide spermatique est fait de millions de petites cellules vivantes, dont une suffit, lorsqu\u2019elle rencontre la cellule form\u00e9e dans le corps de la femme, pour cr\u00e9er un b\u00e9b\u00e9 \u00bb. <\/p>\n\n\n\n<p>Une telle information \u00e0 la fois pr\u00e9cise et d\u00e9dramatis\u00e9e aide \u00e0  surmonter  les  probl\u00e8mes  qui  surgissent  in\u00e9vitablement  \u00e0  l\u2019occasion  des  transformations pubertaires. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qui doit parler ? <\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\">Les parents sont certainement les \u00e9ducateurs sexuels les plus valables parce que la nature leur a implicitement confi\u00e9 cette responsabilit\u00e9. Selon les chercheurs, laisser cette t\u00e2che \u00e0 une tierce personne repr\u00e9sente un v\u00e9ritable danger. Il y a danger que devant la d\u00e9mission de ses parents, l\u2019adolescent ne leur retire (\u00e0 l\u2019avenir) une confiance jusqu\u2019alors illimit\u00e9e qu\u2019il pourra reporter sur l\u2019\u00e9ducateur qui a pris leur place. Il y a danger aussi qu\u2019il pense logiquement que, si ses parents lui refusent des explications sur les r\u00e9alit\u00e9s de la vie, c\u2019est parce qu\u2019elles sont laides et honteuses. Ainsi risque-t-il d\u00e8s l\u2019instant m\u00eame d\u2019en ressentir un sentiment confus de honte qui peut \u00eatre \u00e0 l\u2019origine de l\u2019\u00e9chec de sa sexualit\u00e9. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">En mati\u00e8re d\u2019\u00e9ducation sexuelle, il est difficile d\u2019\u00e9tablir des r\u00e8gles absolues ou des bar\u00e8mes, parce qu\u2019il ne s\u2019agit pas d\u2019une science. Les adolescents sont diff\u00e9rents dans une m\u00eame famille et d\u2019une famille \u00e0 l\u2019autre. L\u2019esprit de curiosit\u00e9 de l\u2019adolescent dans le domaine varie selon les conditions de vie de la famille et l\u2019\u00e2ge de l\u2019adolescent. D\u2019embl\u00e9e, nous dirons qu\u2019en mati\u00e8re de sexualit\u00e9, si nous donnons du premier coup la r\u00e9ponse \u00e0 la fois juste et satisfaisante, l\u2019adolescent (notre enfant) nous consid\u00e9rera d\u00e9sormais comme un interlocuteur valable. Mais ces r\u00e9ponses doivent \u00eatre graduelles, selon l\u2019\u00e2ge et les besoins de l\u2019adolescent. <\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong>La  vraie  t\u00e2che  \u00e9ducative  commence  quand  les  parents  valorisent  les  \u00e9l\u00e9ments  affectifs, spirituels et moraux de la vie de couple. Une bonne \u00e9ducation sexuelle n\u00e9cessite des explications pr\u00e9cises et progressives d\u2019ordre sexuel, physique  et  anatomo-physiologique  doubl\u00e9es  d\u2019une  vraie  \u00e9ducation  affective,  spirituelle  ou morale. <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelques conduites \u00e0 \u00e9viter<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Ne pas tripoter les parties sexuelles de l\u2019enfant<\/li><li>Eviter les rapports sexuels devant les enfants<\/li><li>Vous devez chercher \u00e0 ne pas transf\u00e9rer leurs propres probl\u00e8mes sur leurs enfants<\/li><\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Vous avez des questions sur l&rsquo;\u00e9ducation sexuelle des ados, et vous souhaitez en savoir plus ? Posez votre question sur notre section \u00ab&nbsp;<a href=\"https:\/\/monpsychomag.com\/index.php\/monpsycho-jai-une-question\/\"><strong>Questions<\/strong><\/a>&nbsp;\u00bb . Et n\u2019oubliez pas de commenter l\u2019article pour expliquer votre point de vue sur <em>l&rsquo;\u00e9ducation sexuelle des ados<\/em>, que vous viviez cette situation de pr\u00e8s ou de loin.<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"has-text-align-justify\"><em><strong>Je vous donne rendez-vous dans le prochain num\u00e9ro. A tr\u00e8s bient\u00f4t.<\/strong><\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Heureux de vous retrouver encore dans ce nouveau num\u00e9ro autour<\/p>\n","protected":false},"author":132,"featured_media":3220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[607],"tags":[235,650,784,180],"class_list":["post-3203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education","tag-education","tag-magazine-africain-de-psychologie","tag-marc-efavi","tag-sexualite"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2021\/07\/Screenshot_20210706-100147-e1625585843487.png?fit=638%2C403&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/132"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=3203"}],"version-history":[{"count":5,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3203\/revisions"}],"predecessor-version":[{"id":3225,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/3203\/revisions\/3225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/3220"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=3203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=3203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=3203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}