{"id":263,"date":"2020-07-13T16:02:35","date_gmt":"2020-07-13T16:02:35","guid":{"rendered":"http:\/\/monpsychomag.com\/?p=263"},"modified":"2020-07-13T16:33:12","modified_gmt":"2020-07-13T16:33:12","slug":"solution-daudrey-koubodena-contre-le-viol","status":"publish","type":"post","link":"https:\/\/monpsychomag.com\/index.php\/2020\/07\/13\/solution-daudrey-koubodena-contre-le-viol\/","title":{"rendered":"Audrey KOUBODENA contre le viol"},"content":{"rendered":"<div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n<p>Chaque ann\u00e9e, plus de 5% de femmes sont victimes du <a href=\"https:\/\/www.google.com\/url?sa=t&amp;source=web&amp;rct=j&amp;url=https:\/\/fr.m.wikipedia.org\/wiki\/Viol&amp;ved=2ahUKEwimyoORzMrqAhXNNcAKHQJzAqUQFjAFegQIAhAB&amp;usg=AOvVaw3PaG0gXFm--0iGdB1aSUiC\">viol<\/a> ou de tentative de viol. Le ph\u00e9nom\u00e8ne devient de plus en plus flagrant, malgr\u00e9 les vagues de sensibilisation et de conscientisation. Est-ce un refus de compr\u00e9hension des agresseurs ? Est-ce que les femmes auraient favoris\u00e9 ce fl\u00e9au sans le savoir ? Dans cet article <a href=\"https:\/\/audreyjoyceblog.wordpress.com\">Audrey Koubodena<\/a>, diplomate, <a href=\"https:\/\/www.google.com\/url?sa=t&amp;source=web&amp;rct=j&amp;url=https:\/\/diplomeo.com\/formations-metier-pour-devenir-blogueur\/amp&amp;ved=2ahUKEwii2NOLzMrqAhVGXsAKHbYeCQEQFjAAegQIAhAB&amp;usg=AOvVaw1TLbRFsWpjAmFq_IwuraDJ&amp;ampcf=1\">blogueuse<\/a>, promotrice des droits humains et engag\u00e9e dans le social apporte sa contribution pour venir \u00e0 bout de ce fl\u00e9au.<\/p>\n\n\n\n<p><strong>Monpsychomag<\/strong> : Bonjour Audrey, vous \u00eates sur le site Monpsychomag. Pr\u00e9sentez-vous \u00e0 nos <a href=\"http:\/\/www.monpsychomag.com\">lecteurs<\/a>.<\/p>\n\n\n\n<p><strong>Mme Audrey<\/strong>:Je suis Audrey Tifoumnaka KOUBODENA, diplomate et juriste publiciste. Je suis en service au Minist\u00e8re des Affaires \u00e9trang\u00e8res et engag\u00e9e dans le social par la promotion des droits humains. Passionn\u00e9e de lecture et d\u2019\u00e9criture, je suis blogueuse \u00e0 mes heures perdues.<\/p>\n\n\n\n<p><strong>Monpsychomag<\/strong> : Quand parle-t-on de viol ?<\/p>\n\n\n\n<p><strong>Mme Audrey<\/strong> : Le viol est un acte par lequel une personne force une autre \u00e0 avoir des relations sexuelles avec elle, par violence. Il s\u2019agit de tout acte de p\u00e9n\u00e9tration vaginale, anale ou buccale ou de quelle nature qu\u2019il soit \u00e0 but sexuel impos\u00e9 \u00e0 autrui sans son consentement en usant d\u2019une partie de son corps ou d\u2019un objet, par violence, contrainte ou surprise.<\/p>\n\n\n\n<p><strong>Monpsychomag<\/strong> : Selon vous, qu&rsquo;est-ce qui expliquerait l&rsquo;augmentation de ce fl\u00e9au au sein de notre soci\u00e9t\u00e9, aujourd&rsquo;hui ?<\/p><div class=\"db567aefa9b9073415b194386f2f1045\" data-index=\"3\" style=\"float: none; margin:0px 0 0px 0; text-align:center;\">\n<!-- Code \u00e0 placer \u00e0 l'endroit ou vous voulez afficher les publicit\u00e9s -->\r\n<div id=\"afrikad-slot-1741-p-1\"\r\n     data-afrikad\r\n     data-slot-id=\"1741\" \r\n     data-dynamic-countries=\"tg\"\r\n     style=\"margin: auto; width: 300px; height: 275px;\"><\/div>\r\n\r\n<!-- Code \u00e0 placer de pr\u00e9ference une seule fois en bas de page -->\r\n<script>\r\n    (function (d) {\r\n        if (window.afrikadInit == null) {\r\n            window.afrikadInit = function (sdk) {\r\n                sdk.autoload();\r\n            };\r\n        }\r\n\r\n        var js, ajs = d.getElementsByTagName('script')[0];\r\n        if (d.getElementById('afrikad-sdk')) {\r\n            return;\r\n        }\r\n        js = d.createElement('script');\r\n        js.id = \"afrikad-sdk\";\r\n        js.src = \"https:\/\/www.afrikad.com\/build\/latest\/js\/sdk.js\";\r\n        ajs.parentNode.insertBefore(js, ajs);\r\n    }(document));\r\n<\/script>\n<\/div>\n\n\n\n\n<p><strong>Mme Audrey<\/strong> : Le viol ou les violences sexuelles d&rsquo;une mani\u00e8re g\u00e9n\u00e9rale ont toujours exist\u00e9 depuis la nuit\u00a0des temps. Je ne pense pas que ce fl\u00e9au ait augment\u00e9 derni\u00e8rement. A mon avis, c\u2019est juste que de nos jours, le sujet n\u2019est plus tabou et beaucoup de filles qui en sont victimes ont le courage d\u2019en  parler.<\/p>\n\n\n\n<p><strong>Monpsychomag<\/strong> : Dans \u00ab\u00a0Pourquoi je ne porte que des pantalons\u00a0\u00bb publi\u00e9&nbsp; le 25 juin 2020 sur votre blog, vous parliez de ce fl\u00e9au. Quel message pr\u00e9cis v\u00e9hiculez-vous dans cette publication ?<\/p>\n\n\n\n<p><strong>Mme Audrey<\/strong> : J\u2019ai en effet consacr\u00e9 un billet \u00e0 cette th\u00e9matique qui est d\u2019actualit\u00e9, dont le lien est le suivant&nbsp;<a href=\"https:\/\/bit.ly\/3iYWZO7\">https:\/\/bit.ly\/3iYWZO7<\/a>. Il s\u2019agit pour ma part d\u2019inviter les femmes \u00e0 ne pas s\u2019enfermer dans le silence lorsqu\u2019elles subissent des violences. En parler, d\u00e9noncer les auteurs et chercher de l\u2019aide sont tr\u00e8s importants si la soci\u00e9t\u00e9 veut \u00e9liminer ce fl\u00e9au.<\/p>\n\n\n\n<p><strong>Monpsychomag<\/strong> : Selon vous comment la soci\u00e9t\u00e9&nbsp; actuelle pourrait-elle r\u00e9duire ce mal ?<\/p>\n\n\n\n<p><strong>Mme Audrey<\/strong> : La soci\u00e9t\u00e9 actuelle pourra r\u00e9duire le fl\u00e9au du viol en multipliant des actions comme la sensibilisation dans tous les milieux, la promotion des droits des femmes, l\u2019\u00e9ducation sexuelle des jeunes pour une sexualit\u00e9 plus responsable, le refus de l\u2019impunit\u00e9 et de la culture du silence, en sanctionnant syst\u00e9matiquement les auteurs de ces actes, entre autres.<\/p>\n\n\n\n<p><strong>Monpsychomag<\/strong> : Merci pour vos apports. Avez-vous un dernier mot ?<\/p>\n\n\n\n<p><strong>Mme Audrey<\/strong> : Je saisis cette occasion pour vous f\u00e9liciter pour tout le travail que vous abattez, et pour souhaiter plein succ\u00e8s \u00e0 vos projets. Je vous remercie pour l\u2019attention et j&rsquo;invite vos lecteurs \u00e0 faire un tour sur mon blog  <a href=\"https:\/\/bit.ly\/32cr077\">https:\/\/bit.ly\/32cr077<\/a><\/p>\n\n\n\n<p><strong>Monpsychomag<\/strong> : Merci de nous avoir accord\u00e9 votre temps et courage \u00e0 vous pour la suite de vos actions<\/p>\n\n\n\n<p><strong>Mme Audrey<\/strong>: Je vous en prie.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Chaque ann\u00e9e, plus de 5% de femmes sont victimes de viol ou de tentative de viol. Le ph\u00e9nom\u00e8ne devient de plus en plus flagrant, malgr\u00e9 les vagues de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[89,91,90],"class_list":["post-263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bon-a-savoir","tag-audrey-koubodena","tag-blogueuse","tag-viol"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/monpsychomag.com\/wp-content\/uploads\/2020\/07\/Resizer_15946549455300.jpg?fit=800%2C530&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":8,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/263\/revisions"}],"predecessor-version":[{"id":273,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/posts\/263\/revisions\/273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media\/264"}],"wp:attachment":[{"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/media?parent=263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/categories?post=263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monpsychomag.com\/index.php\/wp-json\/wp\/v2\/tags?post=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}